{"id":2171,"date":"2016-10-09T13:06:00","date_gmt":"2016-10-09T06:06:00","guid":{"rendered":"http:\/\/snasui.com\/wordpress\/?p=2171"},"modified":"2025-09-12T12:31:57","modified_gmt":"2025-09-12T05:31:57","slug":"selectdatawithconditions","status":"publish","type":"post","link":"https:\/\/snasui.com\/wordpress\/selectdatawithconditions\/","title":{"rendered":"\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e21\u0e32\u0e41\u0e2a\u0e14\u0e07\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23"},"content":{"rendered":"\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wlEmoticon wlEmoticon-openmouthedsmile\" style=\"border-style: none;\" src=\"https:\/\/i0.wp.com\/snasui.com\/wordpress\/wp-content\/uploads\/2016\/10\/wlEmoticon-openmouthedsmile.png\" alt=\"Open-mouthed smile\"\/> \u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e43\u0e14 \u0e46 \u0e21\u0e32\u0e41\u0e2a\u0e14\u0e07\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e19\u0e31\u0e49\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e22\u0e27\u0e34\u0e18\u0e35 \u0e40\u0e0a\u0e48\u0e19 Advanced Filter, Array Fomulas, PivotTable, Consolidation \u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e14\u0e49\u0e27\u0e22 VBA \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e01\u0e25\u0e48\u0e32\u0e27\u0e21\u0e32\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e33\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e2d\u0e25\u0e31\u0e21\u0e19\u0e4c\u0e0a\u0e48\u0e27\u0e22\u0e17\u0e35\u0e48\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e15\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e14 \u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e01\u0e31\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e04\u0e27\u0e23\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>\u0e42\u0e14\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e41\u0e25\u0e49\u0e27\u0e43\u0e19\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e21\u0e35\u0e2a\u0e39\u0e15\u0e23\u0e43\u0e14 \u0e46 \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e32\u0e01\u0e21\u0e35\u0e01\u0e47\u0e04\u0e27\u0e23\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e2b\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e21\u0e35\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e41\u0e25\u0e30\u0e1a\u0e32\u0e07\u0e04\u0e2d\u0e25\u0e31\u0e21\u0e19\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e39\u0e15\u0e23\u0e41\u0e25\u0e49\u0e27 \u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e1f\u0e25\u0e4c\u0e21\u0e35\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e35\u0e01\u0e21\u0e32\u0e01\u0e17\u0e31\u0e49\u0e07\u0e43\u0e0a\u0e49\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e33\u0e19\u0e27\u0e13\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32\u0e1b\u0e01\u0e15\u0e34<\/p>\n\n\n\n<p>\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48\u0e08\u0e30\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e04\u0e2d\u0e25\u0e31\u0e21\u0e19\u0e4c\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e19\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e30\u0e1a\u0e38\u0e27\u0e48\u0e32\u0e1a\u0e23\u0e23\u0e17\u0e31\u0e14\u0e43\u0e14\u0e40\u0e02\u0e49\u0e32\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e41\u0e25\u0e30\u0e16\u0e39\u0e01\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e44\u0e1b\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25 <span style=\"color: #c0504d;\">\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e07\u0e48\u0e32\u0e22<\/span>\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e36\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u0e2a\u0e30\u0e14\u0e27\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e01\u0e49\u0e44\u0e02\u0e2a\u0e39\u0e15\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e40\u0e2d\u0e07\u0e43\u0e19\u0e20\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07 \u0e42\u0e14\u0e22\u0e2a\u0e21\u0e21\u0e38\u0e15\u0e34\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e42\u0e14\u0e22\u0e21\u0e35 \u201c\u0e1b\u0e35\u201d \u0e41\u0e25\u0e30 \u201c\u0e40\u0e14\u0e37\u0e2d\u0e19\u201d \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u270d\ufe0f <span>\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e08\u0e30\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e22\u0e39\u0e48 3 \u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2b\u0e25\u0e31\u0e01\u0e04\u0e37\u0e2d<\/span><\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li>\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25<\/li>\n\n\n\n<li>\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02<\/li>\n\n\n\n<li>\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\uddbc\ufe0f <span>\u0e20\u0e32\u0e1e\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e42\u0e14\u0e22\u0e23\u0e30\u0e1a\u0e38\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23<\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image alignnone\"><a href=\"https:\/\/i0.wp.com\/snasui.com\/wordpress\/wp-content\/uploads\/2016\/10\/SelectDataWithMultiConditions_001.png\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/snasui.com\/wordpress\/wp-content\/uploads\/2016\/10\/SelectDataWithMultiConditions_001_thumb.png\" alt=\"SelectDataWithMultiConditions_001\"\/><\/a><figcaption class=\"wp-element-caption\">\u0e20\u0e32\u0e1e 1 \u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span>\u0e08\u0e32\u0e01\u0e20\u0e32\u0e1e\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e19 \u0e21\u0e35\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/span><\/h3>\n\n\n\n<p><strong>A. \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01 \u201c\u0e1b\u0e35\u201d \u0e41\u0e25\u0e30 \u201c\u0e40\u0e14\u0e37\u0e2d\u0e19\u201d \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e35\u0e22\u0e4c\u0e25\u0e07\u0e44\u0e1b\u0e43\u0e19\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>\u0e04\u0e25\u0e34\u0e01\u0e17\u0e35\u0e48 J2 > \u0e40\u0e02\u0e49\u0e32\u0e40\u0e21\u0e19\u0e39 Data > Data Validation \u0e41\u0e25\u0e49\u0e27\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e15\u0e32\u0e21\u0e20\u0e32\u0e1e<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image alignnone\"><a href=\"https:\/\/i0.wp.com\/snasui.com\/wordpress\/wp-content\/uploads\/2016\/10\/SelectDataWithMultiConditions_002.png\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/snasui.com\/wordpress\/wp-content\/uploads\/2016\/10\/SelectDataWithMultiConditions_002_thumb.png\" alt=\"SelectDataWithMultiConditions_002\"\/><\/a><figcaption class=\"wp-element-caption\">\u0e20\u0e32\u0e1e 2 \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e1b\u0e35<\/figcaption><\/figure>\n\n\n\n<p>\u0e04\u0e25\u0e34\u0e01\u0e17\u0e35\u0e48 J3 > \u0e40\u0e02\u0e49\u0e32\u0e40\u0e21\u0e19\u0e39 Data > Data Validation \u0e41\u0e25\u0e49\u0e27\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e15\u0e32\u0e21\u0e20\u0e32\u0e1e<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone\"><a href=\"https:\/\/i0.wp.com\/snasui.com\/wordpress\/wp-content\/uploads\/2016\/10\/SelectDataWithMultiConditions_003.png\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/snasui.com\/wordpress\/wp-content\/uploads\/2016\/10\/SelectDataWithMultiConditions_003_thumb.png\" alt=\"SelectDataWithMultiConditions_003\"\/><\/a><figcaption class=\"wp-element-caption\">\u0e20\u0e32\u0e1e 3 \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e40\u0e14\u0e37\u0e2d\u0e19<\/figcaption><\/figure>\n\n\n\n<p><strong>B. \u0e40\u0e02\u0e35\u0e22\u0e19\u0e2a\u0e39\u0e15\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e36\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e21\u0e32\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e40\u0e25\u0e37\u0e2d\u0e01 \u201c\u0e40\u0e14\u0e37\u0e2d\u0e19\u201d \u0e41\u0e25\u0e30 \u201c\u0e1b\u0e35\u201d<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>\u0e40\u0e0b\u0e25\u0e25\u0e4c J5 \u0e04\u0e35\u0e22\u0e4c\u0e2a\u0e39\u0e15\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e1e\u0e1a\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e01\u0e35\u0e48\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23<br \/><code><span style=\"color: #0000ff; font-family: terminal, monaco, monospace;\">=COUNTIFS($B$2:$B$3000,J2,$C$2:$C$3000,J3)<\/span><\/code><br \/>Enter<\/li>\n\n\n\n<li>\u0e40\u0e0b\u0e25\u0e25\u0e4c G2 \u0e04\u0e35\u0e22\u0e4c\u0e2a\u0e39\u0e15\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e27\u0e48\u0e32\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e43\u0e14\u0e40\u0e02\u0e49\u0e32\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e43\u0e2b\u0e49\u0e41\u0e2a\u0e14\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e25\u0e33\u0e14\u0e31\u0e1a<br \/><code><span style=\"color: #0000ff; font-family: terminal, monaco, monospace;\">=IF(AND(B2=$J$2,C2=$J$3),COUNT(G$1:G1)+1,\"\")<\/span><\/code><br \/>Enter > Copy \u0e25\u0e07\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u0e15\u0e32\u0e21\u0e08\u0e33\u0e19\u0e27\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e21\u0e35<\/li>\n\n\n\n<li>\u0e40\u0e0b\u0e25\u0e25\u0e4c I6 \u0e04\u0e35\u0e22\u0e4c\u0e2a\u0e39\u0e15\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02<br \/><code><span style=\"color: #0000ff; font-family: terminal, monaco, monospace;\">=IF(ROWS(I$6:I6)>$J$4,\"\",LOOKUP(ROWS(I$6:I6),$G$2:$G$3000,A$2:A$3000))<\/span><\/code><br \/>Enter > Copy \u0e44\u0e1b\u0e14\u0e49\u0e32\u0e19\u0e02\u0e27\u0e32\u0e16\u0e36\u0e07 N6 \u0e41\u0e25\u0e49\u0e27 Copy I6:N6 \u0e25\u0e07\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07<\/li>\n<\/ol>\n\n\n\n<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e25\u0e37\u0e2d\u0e01 \u201c\u0e1b\u0e35\u201d \u0e41\u0e25\u0e30 \u201c\u0e40\u0e14\u0e37\u0e2d\u0e19\u201d \u0e17\u0e35\u0e48\u0e40\u0e0b\u0e25\u0e25\u0e4c J2 \u0e41\u0e25\u0e30 J3 \u0e41\u0e25\u0e49\u0e27 \u0e08\u0e30\u0e19\u0e33\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e15\u0e23\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e21\u0e32\u0e41\u0e2a\u0e14\u0e07 <img data-recalc-dims=\"1\" decoding=\"async\" class=\"wlEmoticon wlEmoticon-thumbsup\" style=\"border-style: none;\" src=\"https:\/\/i0.wp.com\/snasui.com\/wordpress\/wp-content\/uploads\/2016\/10\/wlEmoticon-thumbsup.png\" alt=\"Thumbs up\"\/><\/p>\n\n\n\n<p><span style=\"color: #999999;\"><strong>Revised:<\/strong> January 29, 2017 at 07:02<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e43\u0e19 Excel \u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02 \u0e40\u0e0a\u0e48\u0e19 \u201c\u0e1b\u0e35\u201d \u0e41\u0e25\u0e30 \u201c\u0e40\u0e14\u0e37\u0e2d\u0e19\u201d \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49 Data Validation \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e39\u0e15\u0e23 COUNTIFS, IF \u0e41\u0e25\u0e30 LOOKUP \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07<\/p>\n","protected":false},"author":1,"featured_media":2192,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[149],"tags":[81,168,8,12,46,49],"class_list":["post-2171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tips-and-tricks","tag-and","tag-counifs","tag-count","tag-if","tag-lookup","tag-rows"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 | \u0e14\u0e36\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e39\u0e15\u0e23 Excel<\/title>\n<meta name=\"description\" content=\"\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e21\u0e32\u0e41\u0e2a\u0e14\u0e07\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u201c\u0e1b\u0e35\u201d \u0e41\u0e25\u0e30 \u201c\u0e40\u0e14\u0e37\u0e2d\u0e19\u201d \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49 Data Validation \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e39\u0e15\u0e23 Excel\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/snasui.com\/wordpress\/selectdatawithconditions\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 | \u0e14\u0e36\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e39\u0e15\u0e23 Excel\" \/>\n<meta property=\"og:description\" content=\"\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e21\u0e32\u0e41\u0e2a\u0e14\u0e07\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u201c\u0e1b\u0e35\u201d \u0e41\u0e25\u0e30 \u201c\u0e40\u0e14\u0e37\u0e2d\u0e19\u201d \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49 Data Validation \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e39\u0e15\u0e23 Excel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/snasui.com\/wordpress\/selectdatawithconditions\/\" \/>\n<meta property=\"og:site_name\" content=\"Snasui Enterprise Solutions\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/santipong.nasui\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/santipong.nasui\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-09T06:06:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-12T05:31:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/snasui.com\/wordpress\/wp-content\/uploads\/2016\/11\/baby-84626_960_7201.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"snasui\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@snasui\" \/>\n<meta name=\"twitter:site\" content=\"@snasui\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"snasui\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/selectdatawithconditions\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/selectdatawithconditions\\\/\"},\"author\":{\"name\":\"snasui\",\"@id\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/#\\\/schema\\\/person\\\/04de25027843e412280da0b02dd55fb6\"},\"headline\":\"\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e21\u0e32\u0e41\u0e2a\u0e14\u0e07\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\",\"datePublished\":\"2016-10-09T06:06:00+00:00\",\"dateModified\":\"2025-09-12T05:31:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/selectdatawithconditions\\\/\"},\"wordCount\":34,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/#\\\/schema\\\/person\\\/04de25027843e412280da0b02dd55fb6\"},\"image\":{\"@id\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/selectdatawithconditions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/snasui.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/baby-84626_960_7201.jpg?fit=960%2C640&ssl=1\",\"keywords\":[\"And\",\"Counifs\",\"Count\",\"If\",\"Lookup\",\"Rows\"],\"articleSection\":[\"Tips and Tricks\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/snasui.com\\\/wordpress\\\/selectdatawithconditions\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/selectdatawithconditions\\\/\",\"url\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/selectdatawithconditions\\\/\",\"name\":\"\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 | \u0e14\u0e36\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e39\u0e15\u0e23 Excel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/selectdatawithconditions\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/selectdatawithconditions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/snasui.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/baby-84626_960_7201.jpg?fit=960%2C640&ssl=1\",\"datePublished\":\"2016-10-09T06:06:00+00:00\",\"dateModified\":\"2025-09-12T05:31:57+00:00\",\"description\":\"\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e21\u0e32\u0e41\u0e2a\u0e14\u0e07\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u201c\u0e1b\u0e35\u201d \u0e41\u0e25\u0e30 \u201c\u0e40\u0e14\u0e37\u0e2d\u0e19\u201d \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49 Data Validation \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e39\u0e15\u0e23 Excel\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/selectdatawithconditions\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/snasui.com\\\/wordpress\\\/selectdatawithconditions\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/selectdatawithconditions\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/snasui.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/baby-84626_960_7201.jpg?fit=960%2C640&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/snasui.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/baby-84626_960_7201.jpg?fit=960%2C640&ssl=1\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/selectdatawithconditions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e21\u0e32\u0e41\u0e2a\u0e14\u0e07\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/\",\"name\":\"Excel Tips and Tricks\",\"description\":\"Enterprise Automation Solutions for Finance &amp; Business\",\"publisher\":{\"@id\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/#\\\/schema\\\/person\\\/04de25027843e412280da0b02dd55fb6\"},\"alternateName\":\"SatiFlow\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/#\\\/schema\\\/person\\\/04de25027843e412280da0b02dd55fb6\",\"name\":\"snasui\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/wp-content\\\/uploads\\\/nsl_avatars\\\/ce474b46e4f6c114aac81892c3c0d503.jpg\",\"url\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/wp-content\\\/uploads\\\/nsl_avatars\\\/ce474b46e4f6c114aac81892c3c0d503.jpg\",\"contentUrl\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/wp-content\\\/uploads\\\/nsl_avatars\\\/ce474b46e4f6c114aac81892c3c0d503.jpg\",\"width\":200,\"height\":200,\"caption\":\"snasui\"},\"logo\":{\"@id\":\"https:\\\/\\\/snasui.com\\\/wordpress\\\/wp-content\\\/uploads\\\/nsl_avatars\\\/ce474b46e4f6c114aac81892c3c0d503.jpg\"},\"description\":\"MBA in Accounting, MVP Excel 2010-2020, MOS\",\"sameAs\":[\"https:\\\/\\\/www.snasui.com\",\"https:\\\/\\\/www.facebook.com\\\/santipong.nasui\",\"https:\\\/\\\/www.instagram.com\\\/santipong__nasui\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/santipong-nasui-58714726\\\/\",\"https:\\\/\\\/x.com\\\/snasui\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/snasui\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 | \u0e14\u0e36\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e39\u0e15\u0e23 Excel","description":"\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e21\u0e32\u0e41\u0e2a\u0e14\u0e07\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u201c\u0e1b\u0e35\u201d \u0e41\u0e25\u0e30 \u201c\u0e40\u0e14\u0e37\u0e2d\u0e19\u201d \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49 Data Validation \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e39\u0e15\u0e23 Excel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/snasui.com\/wordpress\/selectdatawithconditions\/","og_locale":"en_US","og_type":"article","og_title":"\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 | \u0e14\u0e36\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e39\u0e15\u0e23 Excel","og_description":"\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e21\u0e32\u0e41\u0e2a\u0e14\u0e07\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u201c\u0e1b\u0e35\u201d \u0e41\u0e25\u0e30 \u201c\u0e40\u0e14\u0e37\u0e2d\u0e19\u201d \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49 Data Validation \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e39\u0e15\u0e23 Excel","og_url":"https:\/\/snasui.com\/wordpress\/selectdatawithconditions\/","og_site_name":"Snasui Enterprise Solutions","article_publisher":"https:\/\/www.facebook.com\/santipong.nasui","article_author":"https:\/\/www.facebook.com\/santipong.nasui","article_published_time":"2016-10-09T06:06:00+00:00","article_modified_time":"2025-09-12T05:31:57+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/snasui.com\/wordpress\/wp-content\/uploads\/2016\/11\/baby-84626_960_7201.jpg","type":"image\/jpeg"}],"author":"snasui","twitter_card":"summary_large_image","twitter_creator":"@snasui","twitter_site":"@snasui","twitter_misc":{"Written by":"snasui","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/snasui.com\/wordpress\/selectdatawithconditions\/#article","isPartOf":{"@id":"https:\/\/snasui.com\/wordpress\/selectdatawithconditions\/"},"author":{"name":"snasui","@id":"https:\/\/snasui.com\/wordpress\/#\/schema\/person\/04de25027843e412280da0b02dd55fb6"},"headline":"\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e21\u0e32\u0e41\u0e2a\u0e14\u0e07\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23","datePublished":"2016-10-09T06:06:00+00:00","dateModified":"2025-09-12T05:31:57+00:00","mainEntityOfPage":{"@id":"https:\/\/snasui.com\/wordpress\/selectdatawithconditions\/"},"wordCount":34,"commentCount":0,"publisher":{"@id":"https:\/\/snasui.com\/wordpress\/#\/schema\/person\/04de25027843e412280da0b02dd55fb6"},"image":{"@id":"https:\/\/snasui.com\/wordpress\/selectdatawithconditions\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/snasui.com\/wordpress\/wp-content\/uploads\/2016\/11\/baby-84626_960_7201.jpg?fit=960%2C640&ssl=1","keywords":["And","Counifs","Count","If","Lookup","Rows"],"articleSection":["Tips and Tricks"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/snasui.com\/wordpress\/selectdatawithconditions\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/snasui.com\/wordpress\/selectdatawithconditions\/","url":"https:\/\/snasui.com\/wordpress\/selectdatawithconditions\/","name":"\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 | \u0e14\u0e36\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e39\u0e15\u0e23 Excel","isPartOf":{"@id":"https:\/\/snasui.com\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/snasui.com\/wordpress\/selectdatawithconditions\/#primaryimage"},"image":{"@id":"https:\/\/snasui.com\/wordpress\/selectdatawithconditions\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/snasui.com\/wordpress\/wp-content\/uploads\/2016\/11\/baby-84626_960_7201.jpg?fit=960%2C640&ssl=1","datePublished":"2016-10-09T06:06:00+00:00","dateModified":"2025-09-12T05:31:57+00:00","description":"\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e21\u0e32\u0e41\u0e2a\u0e14\u0e07\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u201c\u0e1b\u0e35\u201d \u0e41\u0e25\u0e30 \u201c\u0e40\u0e14\u0e37\u0e2d\u0e19\u201d \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49 Data Validation \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e39\u0e15\u0e23 Excel","breadcrumb":{"@id":"https:\/\/snasui.com\/wordpress\/selectdatawithconditions\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/snasui.com\/wordpress\/selectdatawithconditions\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/snasui.com\/wordpress\/selectdatawithconditions\/#primaryimage","url":"https:\/\/i0.wp.com\/snasui.com\/wordpress\/wp-content\/uploads\/2016\/11\/baby-84626_960_7201.jpg?fit=960%2C640&ssl=1","contentUrl":"https:\/\/i0.wp.com\/snasui.com\/wordpress\/wp-content\/uploads\/2016\/11\/baby-84626_960_7201.jpg?fit=960%2C640&ssl=1","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/snasui.com\/wordpress\/selectdatawithconditions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/snasui.com\/wordpress\/"},{"@type":"ListItem","position":2,"name":"\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e21\u0e32\u0e41\u0e2a\u0e14\u0e07\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23"}]},{"@type":"WebSite","@id":"https:\/\/snasui.com\/wordpress\/#website","url":"https:\/\/snasui.com\/wordpress\/","name":"Excel Tips and Tricks","description":"Enterprise Automation Solutions for Finance &amp; Business","publisher":{"@id":"https:\/\/snasui.com\/wordpress\/#\/schema\/person\/04de25027843e412280da0b02dd55fb6"},"alternateName":"SatiFlow","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/snasui.com\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/snasui.com\/wordpress\/#\/schema\/person\/04de25027843e412280da0b02dd55fb6","name":"snasui","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/snasui.com\/wordpress\/wp-content\/uploads\/nsl_avatars\/ce474b46e4f6c114aac81892c3c0d503.jpg","url":"https:\/\/snasui.com\/wordpress\/wp-content\/uploads\/nsl_avatars\/ce474b46e4f6c114aac81892c3c0d503.jpg","contentUrl":"https:\/\/snasui.com\/wordpress\/wp-content\/uploads\/nsl_avatars\/ce474b46e4f6c114aac81892c3c0d503.jpg","width":200,"height":200,"caption":"snasui"},"logo":{"@id":"https:\/\/snasui.com\/wordpress\/wp-content\/uploads\/nsl_avatars\/ce474b46e4f6c114aac81892c3c0d503.jpg"},"description":"MBA in Accounting, MVP Excel 2010-2020, MOS","sameAs":["https:\/\/www.snasui.com","https:\/\/www.facebook.com\/santipong.nasui","https:\/\/www.instagram.com\/santipong__nasui\/","https:\/\/www.linkedin.com\/in\/santipong-nasui-58714726\/","https:\/\/x.com\/snasui","https:\/\/www.youtube.com\/user\/snasui"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/snasui.com\/wordpress\/wp-content\/uploads\/2016\/11\/baby-84626_960_7201.jpg?fit=960%2C640&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/snasui.com\/wordpress\/wp-json\/wp\/v2\/posts\/2171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snasui.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/snasui.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/snasui.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/snasui.com\/wordpress\/wp-json\/wp\/v2\/comments?post=2171"}],"version-history":[{"count":11,"href":"https:\/\/snasui.com\/wordpress\/wp-json\/wp\/v2\/posts\/2171\/revisions"}],"predecessor-version":[{"id":7635,"href":"https:\/\/snasui.com\/wordpress\/wp-json\/wp\/v2\/posts\/2171\/revisions\/7635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/snasui.com\/wordpress\/wp-json\/wp\/v2\/media\/2192"}],"wp:attachment":[{"href":"https:\/\/snasui.com\/wordpress\/wp-json\/wp\/v2\/media?parent=2171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/snasui.com\/wordpress\/wp-json\/wp\/v2\/categories?post=2171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/snasui.com\/wordpress\/wp-json\/wp\/v2\/tags?post=2171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}